{"id":42792,"date":"2026-02-10T16:54:13","date_gmt":"2026-02-10T15:54:13","guid":{"rendered":"https:\/\/silviafernandez.com\/clientes-convencion\/del-pozo-novias\/"},"modified":"2026-02-10T16:54:13","modified_gmt":"2026-02-10T15:54:13","slug":"del-pozo-novias","status":"publish","type":"clientes-convencion","link":"https:\/\/silviafernandez.com\/en\/clientes-convencion\/del-pozo-novias\/","title":{"rendered":"Del Pozo Novias"},"content":{"rendered":"","protected":false},"template":"","class_list":["post-42792","clientes-convencion","type-clientes-convencion","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/silviafernandez.com\/en\/wp-json\/wp\/v2\/clientes-convencion\/42792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/silviafernandez.com\/en\/wp-json\/wp\/v2\/clientes-convencion"}],"about":[{"href":"https:\/\/silviafernandez.com\/en\/wp-json\/wp\/v2\/types\/clientes-convencion"}],"wp:attachment":[{"href":"https:\/\/silviafernandez.com\/en\/wp-json\/wp\/v2\/media?parent=42792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}